{"id":5853,"date":"2023-01-18T13:37:20","date_gmt":"2023-01-18T13:37:20","guid":{"rendered":"https:\/\/www.trotajueves.es\/blog\/?p=5853"},"modified":"2025-11-25T22:19:03","modified_gmt":"2025-11-25T22:19:03","slug":"5853","status":"publish","type":"post","link":"https:\/\/www.trotajueves.es\/blog\/archivos\/5853","title":{"rendered":"TROTAVERSO"},"content":{"rendered":"<h2 class=\"clear\"><strong style=\"font-family: 'Dancing Script'; background-color: #d2e0f9;\">TROTAVERSO EN CARABANCHEL, Enero<\/strong><\/h2>\n<div class=\"entry share\">\n<div class=\"entry-inner\">\n<p><a href=\"https:\/\/www.trotajueves.es\/wp-content\/uploads\/2022\/02\/SAL3EM2-scaled.jpg\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7412\" src=\"https:\/\/www.trotajueves.es\/wp-content\/uploads\/2022\/02\/SAL3EM2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Empezamos el a\u00f1o en El Trotajueves con VERSO, en may\u00fasculas.<\/p>\n<p>Como es habitual el pasado jueves 12 de enero, nuestro poeta,<\/p>\n<p>compa\u00f1ero, amigo,\u00a0<em><strong>CARLOS SALEM<\/strong><\/em><\/p>\n<p>volvi\u00f3 a llenar la librer\u00eda de l\u00edrica y Carabanchel de rima.<\/p>\n<p>Tambi\u00e9n nos acompa\u00f1aron la poeta <b>\u00a0ANITA WONHAM\u00a0<\/b><img decoding=\"async\" class=\"aligncenter wp-image-5227 \" src=\"https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2-200x300.jpeg\" alt=\"\" width=\"137\" height=\"206\" srcset=\"https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2-200x300.jpeg 200w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2-100x150.jpeg 100w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2-768x1153.jpeg 768w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2-682x1024.jpeg 682w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2-1023x1536.jpeg 1023w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2020\/12\/anita2.jpeg 1066w\" sizes=\"(max-width: 137px) 100vw, 137px\" \/><\/p>\n<p>Y la m\u00fasica nos inund\u00f3 a trav\u00e9s de las canciones de <strong>CHEGAG\u00d3MEZ<\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-5854 \" src=\"https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2023\/01\/chega-300x240.jpg\" alt=\"\" width=\"203\" height=\"162\" srcset=\"https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2023\/01\/chega-300x240.jpg 300w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2023\/01\/chega-150x120.jpg 150w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2023\/01\/chega-768x614.jpg 768w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2023\/01\/chega.jpg 1024w\" sizes=\"(max-width: 203px) 100vw, 203px\" \/>Y como es costumbre se cerr\u00f3 con EL MICRO ABIERTO, llenando el barrio de nuevos juglares.<\/p>\n<p><a href=\"https:\/\/youtube.com\/live\/DuDPBdDlfAE?feature=share\" target=\"_blank\" rel=\"noopener\">Como siempre puedes\u00a0 ver el directo en el canal de youtube del El Trotajueves<\/a><\/p>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/youtube.com\/live\/DuDPBdDlfAE?feature=share\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-5415\" src=\"https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2021\/05\/youtube-300x169-1.png\" alt=\"\" width=\"264\" height=\"149\" srcset=\"https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2021\/05\/youtube-300x169-1.png 300w, https:\/\/www.trotajueves.es\/blog\/wp-content\/uploads\/2021\/05\/youtube-300x169-1-150x85.png 150w\" sizes=\"(max-width: 264px) 100vw, 264px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TROTAVERSO EN CARABANCHEL, Enero Empezamos el a\u00f1o en El Trotajueves con VERSO, en may\u00fasculas. Como es habitual el pasado jueves 12 de enero, nuestro poeta, compa\u00f1ero, amigo,\u00a0CARLOS SALEM volvi\u00f3 a llenar la librer\u00eda de&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":5851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[184],"tags":[49,62,100,54,63,27,160,65,5,66],"class_list":["post-5853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trotaverso","tag-carabanchel","tag-escritor","tag-espectaculo-2","tag-gratis","tag-libros","tag-literatura","tag-musica","tag-poema","tag-poesia","tag-poeta"],"_links":{"self":[{"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/posts\/5853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/comments?post=5853"}],"version-history":[{"count":1,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/posts\/5853\/revisions"}],"predecessor-version":[{"id":6767,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/posts\/5853\/revisions\/6767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/media\/5851"}],"wp:attachment":[{"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/media?parent=5853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/categories?post=5853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trotajueves.es\/blog\/wp-json\/wp\/v2\/tags?post=5853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}